{"id":1607,"date":"2020-10-05T20:54:49","date_gmt":"2020-10-05T18:54:49","guid":{"rendered":"https:\/\/info.axiz.com\/hpe\/?page_id=1607"},"modified":"2020-10-06T12:21:43","modified_gmt":"2020-10-06T10:21:43","slug":"professional-services-12","status":"publish","type":"page","link":"https:\/\/info.axiz.com\/hpe\/axiz-branded-services\/professional-services-12\/","title":{"rendered":"Professional Services"},"content":{"rendered":"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][split_line_heading animation_type=&#8221;default&#8221;]\n<h2>Hybrid Design\/Build<\/h2>\n[\/split_line_heading][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][image_with_animation image_url=&#8221;1608&#8243; animation=&#8221;Fade In&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_column_text]Using Axiz highly skilled specialist they will help you design and plan the full deployment of your Hybrid infrastructure. This will all be documented and if need be converted to a project plan to best suit your deployment requirements[\/vc_column_text][nectar_btn size=&#8221;medium&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Extra-Color-1&#8243; solid_text_color_override=&#8221;#162b35&#8243; icon_family=&#8221;none&#8221; el_class=&#8221;margin-top-sm&#8221; url=&#8221;\/contact-us\/&#8221; text=&#8221;Contact us&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#162b35&#8243; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_gallery type=&#8221;flickity_style&#8221; images=&#8221;1609,1610,1611&#8243; flickity_spacing=&#8221;default&#8221; flickity_controls=&#8221;material_pagination&#8221; flickity_overflow=&#8221;hidden&#8221; flickity_wrap_around=&#8221;wrap&#8221; flickity_desktop_columns=&#8221;1&#8243; flickity_small_desktop_columns=&#8221;1&#8243; flickity_tablet_columns=&#8221;1&#8243; flickity_image_scale_on_drag=&#8221;true&#8221; flickity_autoplay=&#8221;true&#8221; flickity_box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; onclick=&#8221;link_no&#8221;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243;&#8230;<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":1169,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-1607","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Professional Services - Axiz | HPE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/info.axiz.com\/hpe\/axiz-branded-services\/professional-services-12\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Professional Services - Axiz | HPE\" \/>\n<meta property=\"og:description\" content=\"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243;...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/info.axiz.com\/hpe\/axiz-branded-services\/professional-services-12\/\" \/>\n<meta property=\"og:site_name\" content=\"Axiz | HPE\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-06T10:21:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/info.axiz.com\/hpe\/axiz-branded-services\/professional-services-12\/\",\"url\":\"https:\/\/info.axiz.com\/hpe\/axiz-branded-services\/professional-services-12\/\",\"name\":\"Professional Services - Axiz | HPE\",\"isPartOf\":{\"@id\":\"https:\/\/info.axiz.com\/hpe\/#website\"},\"datePublished\":\"2020-10-05T18:54:49+00:00\",\"dateModified\":\"2020-10-06T10:21:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/info.axiz.com\/hpe\/axiz-branded-services\/professional-services-12\/#breadcrumb\"},\"inLanguage\":\"en-ZA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/info.axiz.com\/hpe\/axiz-branded-services\/professional-services-12\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/info.axiz.com\/hpe\/axiz-branded-services\/professional-services-12\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/info.axiz.com\/hpe\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Axiz Services\",\"item\":\"https:\/\/info.axiz.com\/hpe\/axiz-branded-services\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Professional Services\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/info.axiz.com\/hpe\/#website\",\"url\":\"https:\/\/info.axiz.com\/hpe\/\",\"name\":\"Axiz | HPE\",\"description\":\"Building Ecosystems | Transcending Technologies\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/info.axiz.com\/hpe\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-ZA\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Professional Services - Axiz | HPE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/info.axiz.com\/hpe\/axiz-branded-services\/professional-services-12\/","og_locale":"en_US","og_type":"article","og_title":"Professional Services - Axiz | HPE","og_description":"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243;...","og_url":"https:\/\/info.axiz.com\/hpe\/axiz-branded-services\/professional-services-12\/","og_site_name":"Axiz | HPE","article_modified_time":"2020-10-06T10:21:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/info.axiz.com\/hpe\/axiz-branded-services\/professional-services-12\/","url":"https:\/\/info.axiz.com\/hpe\/axiz-branded-services\/professional-services-12\/","name":"Professional Services - Axiz | HPE","isPartOf":{"@id":"https:\/\/info.axiz.com\/hpe\/#website"},"datePublished":"2020-10-05T18:54:49+00:00","dateModified":"2020-10-06T10:21:43+00:00","breadcrumb":{"@id":"https:\/\/info.axiz.com\/hpe\/axiz-branded-services\/professional-services-12\/#breadcrumb"},"inLanguage":"en-ZA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/info.axiz.com\/hpe\/axiz-branded-services\/professional-services-12\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/info.axiz.com\/hpe\/axiz-branded-services\/professional-services-12\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/info.axiz.com\/hpe\/"},{"@type":"ListItem","position":2,"name":"Axiz Services","item":"https:\/\/info.axiz.com\/hpe\/axiz-branded-services\/"},{"@type":"ListItem","position":3,"name":"Professional Services"}]},{"@type":"WebSite","@id":"https:\/\/info.axiz.com\/hpe\/#website","url":"https:\/\/info.axiz.com\/hpe\/","name":"Axiz | HPE","description":"Building Ecosystems | Transcending Technologies","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/info.axiz.com\/hpe\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-ZA"}]}},"_links":{"self":[{"href":"https:\/\/info.axiz.com\/hpe\/wp-json\/wp\/v2\/pages\/1607","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/info.axiz.com\/hpe\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/info.axiz.com\/hpe\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/info.axiz.com\/hpe\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/info.axiz.com\/hpe\/wp-json\/wp\/v2\/comments?post=1607"}],"version-history":[{"count":2,"href":"https:\/\/info.axiz.com\/hpe\/wp-json\/wp\/v2\/pages\/1607\/revisions"}],"predecessor-version":[{"id":1736,"href":"https:\/\/info.axiz.com\/hpe\/wp-json\/wp\/v2\/pages\/1607\/revisions\/1736"}],"up":[{"embeddable":true,"href":"https:\/\/info.axiz.com\/hpe\/wp-json\/wp\/v2\/pages\/1169"}],"wp:attachment":[{"href":"https:\/\/info.axiz.com\/hpe\/wp-json\/wp\/v2\/media?parent=1607"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}